{"id":11262,"date":"2026-07-02T08:18:57","date_gmt":"2026-07-02T11:18:57","guid":{"rendered":"https:\/\/lipefurniture.com\/?post_type=product&#038;p=11262"},"modified":"2026-07-02T08:22:42","modified_gmt":"2026-07-02T11:22:42","slug":"sergio-rodrigues-poltronas-iab","status":"publish","type":"product","link":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/","title":{"rendered":"Sergio Rodrigues &#8211; Poltronas IAB"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com<\/p>\n<p class=\"p1\">p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins<\/p>\n<p class=\"p1\">em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o<\/p>\n<p class=\"p1\">honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965.<\/p>\n<p class=\"p1\">Medidas: 113 x 60 x 79cm<\/p>","protected":false},"featured_media":10535,"template":"","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[28,15],"product_tag":[154],"class_list":["post-11262","product","type-product","status-publish","has-post-thumbnail","product_cat-poltronas","product_cat-todos","product_tag-venda-especial-v","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lipe - Lipe Furniture\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sergio Rodrigues \u2013 Poltronas IAB - Lipe\" \/>\n\t\t<meta property=\"og:description\" content=\"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-02T11:18:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-02T11:22:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sergio Rodrigues \u2013 Poltronas IAB - Lipe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lipefurniture.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/#listItem\",\"name\":\"Acervo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/#listItem\",\"position\":2,\"name\":\"Acervo\",\"item\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/product-category\\\/todos\\\/#listItem\",\"name\":\"Todos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/product-category\\\/todos\\\/#listItem\",\"position\":3,\"name\":\"Todos\",\"item\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/product-category\\\/todos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#listItem\",\"name\":\"Sergio Rodrigues &#8211; Poltronas IAB\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/#listItem\",\"name\":\"Acervo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#listItem\",\"position\":4,\"name\":\"Sergio Rodrigues &#8211; Poltronas IAB\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/product-category\\\/todos\\\/#listItem\",\"name\":\"Todos\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#itempage\",\"url\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/\",\"name\":\"Sergio Rodrigues \\u2013 Poltronas IAB - Lipe\",\"description\":\"Conjunto de poltronas de audit\\u00f3rio IAB. Estrutura em freij\\u00f3 maci\\u00e7o com p\\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\\u00e7o que permitem o movimento de avan\\u00e7o e recuo. Premiada com men\\u00e7\\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\\u00e7\\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lipefurniture.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/DSC0239.jpg\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#mainImage\",\"width\":2000,\"height\":1335},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#mainImage\"},\"datePublished\":\"2026-07-02T08:18:57-03:00\",\"dateModified\":\"2026-07-02T08:22:42-03:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/#organization\",\"name\":\"lipefurniture.com\",\"description\":\"Lipe Furniture\",\"url\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lipefurniture.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Lipe_Logo-scaled.png\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#organizationLogo\",\"width\":2560,\"height\":2073},\"image\":{\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/acervo\\\/sergio-rodrigues-poltronas-iab\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/\",\"name\":\"lipefurniture.com\",\"description\":\"Lipe Furniture\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/lipefurniture.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sergio Rodrigues \u2013 Poltronas IAB - Lipe","description":"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm","canonical_url":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/lipefurniture.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/acervo\/#listItem","name":"Acervo"}},{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/acervo\/#listItem","position":2,"name":"Acervo","item":"https:\/\/lipefurniture.com\/en\/acervo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/product-category\/todos\/#listItem","name":"Todos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/product-category\/todos\/#listItem","position":3,"name":"Todos","item":"https:\/\/lipefurniture.com\/en\/product-category\/todos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#listItem","name":"Sergio Rodrigues &#8211; Poltronas IAB"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/acervo\/#listItem","name":"Acervo"}},{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#listItem","position":4,"name":"Sergio Rodrigues &#8211; Poltronas IAB","previousItem":{"@type":"ListItem","@id":"https:\/\/lipefurniture.com\/en\/product-category\/todos\/#listItem","name":"Todos"}}]},{"@type":"ItemPage","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#itempage","url":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/","name":"Sergio Rodrigues \u2013 Poltronas IAB - Lipe","description":"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/lipefurniture.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/lipefurniture.com\/wp-content\/uploads\/2026\/06\/DSC0239.jpg","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#mainImage","width":2000,"height":1335},"primaryImageOfPage":{"@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#mainImage"},"datePublished":"2026-07-02T08:18:57-03:00","dateModified":"2026-07-02T08:22:42-03:00"},{"@type":"Organization","@id":"https:\/\/lipefurniture.com\/en\/#organization","name":"lipefurniture.com","description":"Lipe Furniture","url":"https:\/\/lipefurniture.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png","@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#organizationLogo","width":2560,"height":2073},"image":{"@id":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/lipefurniture.com\/en\/#website","url":"https:\/\/lipefurniture.com\/en\/","name":"lipefurniture.com","description":"Lipe Furniture","inLanguage":"en-US","publisher":{"@id":"https:\/\/lipefurniture.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Lipe - Lipe Furniture","og:type":"article","og:title":"Sergio Rodrigues \u2013 Poltronas IAB - Lipe","og:description":"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm","og:url":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/","og:image":"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png","og:image:secure_url":"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png","article:published_time":"2026-07-02T11:18:57+00:00","article:modified_time":"2026-07-02T11:22:42+00:00","twitter:card":"summary_large_image","twitter:title":"Sergio Rodrigues \u2013 Poltronas IAB - Lipe","twitter:description":"Conjunto de poltronas de audit\u00f3rio IAB. Estrutura em freij\u00f3 maci\u00e7o com p\u00e9s em metal tubular cromado, assento e encosto em couro natural e balancins em a\u00e7o que permitem o movimento de avan\u00e7o e recuo. Premiada com men\u00e7\u00e3o honrosa pelo concurso do Instituto dos Arquitetos do Brasil, se\u00e7\u00e3o Rio de Janeiro, em 1965. Medidas: 113 x 60 x 79cm","twitter:image":"https:\/\/lipefurniture.com\/wp-content\/uploads\/2025\/02\/Lipe_Logo-scaled.png"},"aioseo_meta_data":{"post_id":"11262","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-02 11:18:57","updated":"2026-08-25 20:34:30","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lipefurniture.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lipefurniture.com\/en\/acervo\/\" title=\"Acervo\">Acervo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lipefurniture.com\/en\/product-category\/todos\/\" title=\"Todos\">Todos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSergio Rodrigues \u2013 Poltronas IAB\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lipefurniture.com\/en"},{"label":"Acervo","link":"https:\/\/lipefurniture.com\/en\/acervo\/"},{"label":"Todos","link":"https:\/\/lipefurniture.com\/en\/product-category\/todos\/"},{"label":"Sergio Rodrigues &#8211; Poltronas IAB","link":"https:\/\/lipefurniture.com\/en\/acervo\/sergio-rodrigues-poltronas-iab\/"}],"_links":{"self":[{"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/product\/11262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/media?parent=11262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/product_brand?post=11262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/product_cat?post=11262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lipefurniture.com\/en\/wp-json\/wp\/v2\/product_tag?post=11262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}